{"id":5474,"date":"2026-07-13T23:07:40","date_gmt":"2026-07-14T02:07:40","guid":{"rendered":"https:\/\/www.periodicodigitaltuc.com\/?p=5474"},"modified":"2026-07-13T23:07:40","modified_gmt":"2026-07-14T02:07:40","slug":"la-plaza-tematica-recibira-a-los-hinchas-para-ver-argentina-inglaterra","status":"publish","type":"post","link":"https:\/\/periodicodigitaltuc.com\/index.php\/2026\/07\/13\/la-plaza-tematica-recibira-a-los-hinchas-para-ver-argentina-inglaterra\/","title":{"rendered":"LA PLAZA TEM\u00c1TICA RECIBIR\u00c1 A LOS HINCHAS PARA VER ARGENTINA-INGLATERRA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La <strong>Municipalidad de San Miguel de Tucum\u00e1n<\/strong> volver\u00e1 a instalar el <strong>Punto Mundialista<\/strong> este mi\u00e9rcoles 15 de julio en la <strong>Plaza Tem\u00e1tica<\/strong>, ubicada en Congreso y San Lorenzo, para que vecinos y turistas puedan seguir en <strong>pantalla gigante<\/strong> la semifinal del <strong>Mundial 2026<\/strong> entre <strong>Argentina<\/strong> e <strong>Inglaterra<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> La jornada comenzar\u00e1 a las 14 con una previa que incluir\u00e1 juegos, trivias, premios, una feria gastron\u00f3mica y el puesto del <strong>Mega Eco Canje Mundial<\/strong>, donde quienes acerquen materiales reciclables recibir\u00e1n obsequios. A las 16 se transmitir\u00e1 en vivo el partido y habr\u00e1 sillas para mayor comodidad del p\u00fablico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-1024x683.jpg\" alt=\"\" class=\"wp-image-5476\" srcset=\"https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-1024x683.jpg 1024w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-300x200.jpg 300w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-768x512.jpg 768w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-1536x1025.jpg 1536w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-2048x1366.jpg 2048w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-150x100.jpg 150w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-330x220.jpg 330w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-420x280.jpg 420w, https:\/\/periodicodigitaltuc.com\/wp-content\/uploads\/2026\/07\/multimedia.grande.ac37bbc65dc733-510x340.jpg 510w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el Municipio destacaron que el Punto Mundialista se convirti\u00f3 en una verdadera <strong>c\u00e1bala tucumana<\/strong> para acompa\u00f1ar a la <strong>Selecci\u00f3n Argentina<\/strong> durante toda la Copa del Mundo. La subsecretaria de Cultura, <strong>Ana L\u00eda Carbonell<\/strong>, invit\u00f3 a las familias a participar de la propuesta con banderas y camisetas, remarc\u00f3 que se sortear\u00e1n pelotas y remeras durante la previa y pidi\u00f3 vivir la jornada con responsabilidad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, confirm\u00f3 que habr\u00e1 un operativo de seguridad con la Patrulla de Protecci\u00f3n Ciudadana y la Polic\u00eda para garantizar que el evento se desarrolle en un clima de fiesta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de San Miguel de Tucum\u00e1n volver\u00e1 a instalar el Punto Mundialista este mi\u00e9rcoles 15 de julio en la Plaza Tem\u00e1tica, ubicada en Congreso y San Lorenzo, para que vecinos y turistas puedan seguir en pantalla gigante la semifinal del Mundial 2026 entre Argentina e Inglaterra. La jornada comenzar\u00e1 a las 14 con una<\/p>\n","protected":false},"author":2,"featured_media":5475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[607,18],"class_list":["post-5474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-seleccion-argentina","tag-tucuman"],"_links":{"self":[{"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/posts\/5474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/comments?post=5474"}],"version-history":[{"count":1,"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/posts\/5474\/revisions"}],"predecessor-version":[{"id":5477,"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/posts\/5474\/revisions\/5477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/media\/5475"}],"wp:attachment":[{"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/media?parent=5474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/categories?post=5474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicodigitaltuc.com\/index.php\/wp-json\/wp\/v2\/tags?post=5474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}